{"id":248984,"date":"2025-06-23T16:12:17","date_gmt":"2025-06-23T14:12:17","guid":{"rendered":"https:\/\/igmi.esercito.difesa.it\/prodotto\/19286\/"},"modified":"2026-02-22T14:07:18","modified_gmt":"2026-02-22T13:07:18","slug":"19286","status":"publish","type":"product","link":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/19286\/","title":{"rendered":"185198 &#8211; SAN SOSSIO"},"content":{"rendered":"<p>185198 &#8211; SAN SOSSIO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>185198 &#8211; SAN SOSSIO<\/p>\n","protected":false},"featured_media":248982,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[220],"product_tag":[388],"class_list":{"0":"post-248984","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-vertici-trigonometrici","7":"product_tag-elemento-geodetico","9":"first","10":"instock","11":"downloadable","12":"virtual","13":"sold-individually","14":"taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>185198 - SAN SOSSIO - Istituto Geografico Militare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/19286\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"185198 - SAN SOSSIO - Istituto Geografico Militare\" \/>\n<meta property=\"og:description\" content=\"185198 &#8211; SAN SOSSIO\" \/>\n<meta property=\"og:url\" content=\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/19286\/\" \/>\n<meta property=\"og:site_name\" content=\"Istituto Geografico Militare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-22T13:07:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M185198-016426.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"306\" \/>\n\t<meta property=\"og:image:height\" content=\"305\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/19286\/\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/19286\/\",\"name\":\"185198 - SAN SOSSIO - Istituto Geografico Militare\",\"isPartOf\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/19286\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/19286\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M185198-016426.jpg\",\"datePublished\":\"2025-06-23T14:12:17+00:00\",\"dateModified\":\"2026-02-22T13:07:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/19286\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/19286\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/19286\/#primaryimage\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M185198-016426.jpg\",\"contentUrl\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M185198-016426.jpg\",\"width\":306,\"height\":305},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/19286\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/igmi.esercito.difesa.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/igmi.esercito.difesa.it\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"185198 &#8211; SAN SOSSIO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#website\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/en\/\",\"name\":\"Istituto Geografico Militare\",\"description\":\"Ente cartografico dello stato\",\"publisher\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/igmi.esercito.difesa.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#organization\",\"name\":\"Istituto Geografico Militare\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp\",\"contentUrl\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp\",\"width\":1320,\"height\":1696,\"caption\":\"Istituto Geografico Militare\"},\"image\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"185198 - SAN SOSSIO - Istituto Geografico Militare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/19286\/","og_locale":"en_US","og_type":"article","og_title":"185198 - SAN SOSSIO - Istituto Geografico Militare","og_description":"185198 &#8211; SAN SOSSIO","og_url":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/19286\/","og_site_name":"Istituto Geografico Militare","article_modified_time":"2026-02-22T13:07:18+00:00","og_image":[{"width":306,"height":305,"url":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M185198-016426.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/19286\/","url":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/19286\/","name":"185198 - SAN SOSSIO - Istituto Geografico Militare","isPartOf":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/19286\/#primaryimage"},"image":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/19286\/#primaryimage"},"thumbnailUrl":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M185198-016426.jpg","datePublished":"2025-06-23T14:12:17+00:00","dateModified":"2026-02-22T13:07:18+00:00","breadcrumb":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/19286\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/19286\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/19286\/#primaryimage","url":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M185198-016426.jpg","contentUrl":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M185198-016426.jpg","width":306,"height":305},{"@type":"BreadcrumbList","@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/19286\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/igmi.esercito.difesa.it\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/igmi.esercito.difesa.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"185198 &#8211; SAN SOSSIO"}]},{"@type":"WebSite","@id":"https:\/\/igmi.esercito.difesa.it\/en\/#website","url":"https:\/\/igmi.esercito.difesa.it\/en\/","name":"Istituto Geografico Militare","description":"Ente cartografico dello stato","publisher":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/igmi.esercito.difesa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/igmi.esercito.difesa.it\/en\/#organization","name":"Istituto Geografico Militare","url":"https:\/\/igmi.esercito.difesa.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp","contentUrl":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp","width":1320,"height":1696,"caption":"Istituto Geografico Militare"},"image":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product\/248984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/media\/248982"}],"wp:attachment":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/media?parent=248984"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product_brand?post=248984"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product_cat?post=248984"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product_tag?post=248984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}