{"id":306956,"date":"2025-06-25T02:02:24","date_gmt":"2025-06-25T00:02:24","guid":{"rendered":"https:\/\/igmi.esercito.difesa.it\/prodotto\/433353\/"},"modified":"2026-04-25T16:10:10","modified_gmt":"2026-04-25T14:10:10","slug":"433353","status":"publish","type":"product","link":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/433353\/","title":{"rendered":"Staz. 24 Y &#8211; M. Vetta Val di Buggio: Francia &#8211; Localit\u00e0 presa: Serra Monteverde &#8211; LN00015831"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[192,215],"product_tag":[361],"class_list":{"0":"post-306956","1":"product","2":"type-product","3":"status-publish","5":"product_cat-foto-storiche","6":"product_cat-tecnica_risoluzione_foto_storica","7":"product_tag-foto-storica","9":"first","10":"instock","11":"downloadable","12":"virtual","13":"sold-individually","14":"taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Staz. 24 Y - M. Vetta Val di Buggio: Francia - Localit\u00e0 presa: Serra Monteverde - LN00015831 - Istituto Geografico Militare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/433353\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Staz. 24 Y - M. Vetta Val di Buggio: Francia - Localit\u00e0 presa: Serra Monteverde - LN00015831 - Istituto Geografico Militare\" \/>\n<meta property=\"og:url\" content=\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/433353\/\" \/>\n<meta property=\"og:site_name\" content=\"Istituto Geografico Militare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-25T14:10:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/433353\/\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/433353\/\",\"name\":\"Staz. 24 Y - M. Vetta Val di Buggio: Francia - Localit\u00e0 presa: Serra Monteverde - LN00015831 - Istituto Geografico Militare\",\"isPartOf\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#website\"},\"datePublished\":\"2025-06-25T00:02:24+00:00\",\"dateModified\":\"2026-04-25T14:10:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/433353\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/433353\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/433353\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/igmi.esercito.difesa.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/igmi.esercito.difesa.it\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Staz. 24 Y &#8211; M. Vetta Val di Buggio: Francia &#8211; Localit\u00e0 presa: Serra Monteverde &#8211; LN00015831\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#website\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/en\/\",\"name\":\"Istituto Geografico Militare\",\"description\":\"Ente cartografico dello stato\",\"publisher\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/igmi.esercito.difesa.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#organization\",\"name\":\"Istituto Geografico Militare\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp\",\"contentUrl\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp\",\"width\":1320,\"height\":1696,\"caption\":\"Istituto Geografico Militare\"},\"image\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Staz. 24 Y - M. Vetta Val di Buggio: Francia - Localit\u00e0 presa: Serra Monteverde - LN00015831 - Istituto Geografico Militare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/433353\/","og_locale":"en_US","og_type":"article","og_title":"Staz. 24 Y - M. Vetta Val di Buggio: Francia - Localit\u00e0 presa: Serra Monteverde - LN00015831 - Istituto Geografico Militare","og_url":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/433353\/","og_site_name":"Istituto Geografico Militare","article_modified_time":"2026-04-25T14:10:10+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/433353\/","url":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/433353\/","name":"Staz. 24 Y - M. Vetta Val di Buggio: Francia - Localit\u00e0 presa: Serra Monteverde - LN00015831 - Istituto Geografico Militare","isPartOf":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/#website"},"datePublished":"2025-06-25T00:02:24+00:00","dateModified":"2026-04-25T14:10:10+00:00","breadcrumb":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/433353\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/433353\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/433353\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/igmi.esercito.difesa.it\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/igmi.esercito.difesa.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Staz. 24 Y &#8211; M. Vetta Val di Buggio: Francia &#8211; Localit\u00e0 presa: Serra Monteverde &#8211; LN00015831"}]},{"@type":"WebSite","@id":"https:\/\/igmi.esercito.difesa.it\/en\/#website","url":"https:\/\/igmi.esercito.difesa.it\/en\/","name":"Istituto Geografico Militare","description":"Ente cartografico dello stato","publisher":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/igmi.esercito.difesa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/igmi.esercito.difesa.it\/en\/#organization","name":"Istituto Geografico Militare","url":"https:\/\/igmi.esercito.difesa.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp","contentUrl":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp","width":1320,"height":1696,"caption":"Istituto Geografico Militare"},"image":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product\/306956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/media?parent=306956"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product_brand?post=306956"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product_cat?post=306956"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product_tag?post=306956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}