{"id":312826,"date":"2025-06-25T06:21:58","date_gmt":"2025-06-25T04:21:58","guid":{"rendered":"https:\/\/igmi.esercito.difesa.it\/prodotto\/29072\/"},"modified":"2026-02-25T05:42:57","modified_gmt":"2026-02-25T04:42:57","slug":"29072","status":"publish","type":"product","link":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/29072\/","title":{"rendered":"058137 &#8211; TERRASA"},"content":{"rendered":"<p>058137 &#8211; TERRASA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>058137 &#8211; TERRASA<\/p>\n","protected":false},"featured_media":312819,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[220],"product_tag":[388],"class_list":{"0":"post-312826","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-vertici-trigonometrici","7":"product_tag-elemento-geodetico","9":"first","10":"instock","11":"downloadable","12":"virtual","13":"sold-individually","14":"taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>058137 - TERRASA - Istituto Geografico Militare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/29072\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"058137 - TERRASA - Istituto Geografico Militare\" \/>\n<meta property=\"og:description\" content=\"058137 &#8211; TERRASA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/29072\/\" \/>\n<meta property=\"og:site_name\" content=\"Istituto Geografico Militare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T04:42:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M058137-005731.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"305\" \/>\n\t<meta property=\"og:image:height\" content=\"304\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/29072\/\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/29072\/\",\"name\":\"058137 - TERRASA - Istituto Geografico Militare\",\"isPartOf\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/29072\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/29072\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M058137-005731.jpg\",\"datePublished\":\"2025-06-25T04:21:58+00:00\",\"dateModified\":\"2026-02-25T04:42:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/29072\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/29072\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/29072\/#primaryimage\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M058137-005731.jpg\",\"contentUrl\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M058137-005731.jpg\",\"width\":305,\"height\":304},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/29072\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/igmi.esercito.difesa.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/igmi.esercito.difesa.it\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"058137 &#8211; TERRASA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#website\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/en\/\",\"name\":\"Istituto Geografico Militare\",\"description\":\"Ente cartografico dello stato\",\"publisher\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/igmi.esercito.difesa.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#organization\",\"name\":\"Istituto Geografico Militare\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp\",\"contentUrl\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp\",\"width\":1320,\"height\":1696,\"caption\":\"Istituto Geografico Militare\"},\"image\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"058137 - TERRASA - Istituto Geografico Militare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/29072\/","og_locale":"en_US","og_type":"article","og_title":"058137 - TERRASA - Istituto Geografico Militare","og_description":"058137 &#8211; TERRASA","og_url":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/29072\/","og_site_name":"Istituto Geografico Militare","article_modified_time":"2026-02-25T04:42:57+00:00","og_image":[{"width":305,"height":304,"url":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M058137-005731.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/29072\/","url":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/29072\/","name":"058137 - TERRASA - Istituto Geografico Militare","isPartOf":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/29072\/#primaryimage"},"image":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/29072\/#primaryimage"},"thumbnailUrl":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M058137-005731.jpg","datePublished":"2025-06-25T04:21:58+00:00","dateModified":"2026-02-25T04:42:57+00:00","breadcrumb":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/29072\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/29072\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/29072\/#primaryimage","url":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M058137-005731.jpg","contentUrl":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M058137-005731.jpg","width":305,"height":304},{"@type":"BreadcrumbList","@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/29072\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/igmi.esercito.difesa.it\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/igmi.esercito.difesa.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"058137 &#8211; TERRASA"}]},{"@type":"WebSite","@id":"https:\/\/igmi.esercito.difesa.it\/en\/#website","url":"https:\/\/igmi.esercito.difesa.it\/en\/","name":"Istituto Geografico Militare","description":"Ente cartografico dello stato","publisher":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/igmi.esercito.difesa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/igmi.esercito.difesa.it\/en\/#organization","name":"Istituto Geografico Militare","url":"https:\/\/igmi.esercito.difesa.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp","contentUrl":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp","width":1320,"height":1696,"caption":"Istituto Geografico Militare"},"image":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product\/312826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/media\/312819"}],"wp:attachment":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/media?parent=312826"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product_brand?post=312826"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product_cat?post=312826"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product_tag?post=312826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}