{"id":315982,"date":"2025-06-25T08:48:48","date_gmt":"2025-06-25T06:48:48","guid":{"rendered":"https:\/\/igmi.esercito.difesa.it\/prodotto\/376034\/"},"modified":"2026-04-21T05:09:02","modified_gmt":"2026-04-21T03:09:02","slug":"376034","status":"publish","type":"product","link":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/376034\/","title":{"rendered":"MAPPA TOPOGRAFICA DELLA CITTA&#8217; DI NAPOLI E DE&#8217; SUOI CONTORNI &#8211; FOGLIO 6."},"content":{"rendered":"<p>Grande carta in 35 fogli incisa su rame. L&#8217;esecuzione di questa carta venne decretata nel 1750 e commessa a G. Carafa Duca di Noja il quale fu assistito dal &#8220;gromatico Vanti che ne form\u00f2 l&#8217;intera delineazione geometrica&#8221;; l&#8217;incisione in rame venne affidata ai Prof.i Campana, Aloja e Lamarra. Morto il Carafa l&#8217;opera rimase interrotta; essa venne ripresa nel 1769 affidata a Gio. Pignatelli Principe di Monterodumi &#8220;che la orn\u00f2 e condusse in fine&#8221;. Nel 1775 vi furono fatte le correzioni ed aggiornamenti a cura del Prof. di Architettura e Matematica Niccol\u00f2 Carletti che ci aggiunse anche una lunga &#8220;Spiegazione storiografica dell&#8217;antico e moderno&#8221;.<br \/>\nIl foglio N\u00b0 1 contiene la seguente dedica: &#8220;Alla Maest\u00e0- di Carlo III- Re delle Spagne- Pio Felice Augusto. Padre della P.- Questa mappa Topografica- di Napoli e dei Contorni- Incominciata nel suo felicissimo Governo &#8211; da Giovanni Carafa Duca di Noja- a pubbliche spese- e perfezionata nel presente-di Ferdinando IV- Re delle due Sicilie- Principe ottimo indulgentissimo- L&#8217;Ordine ed il Popolo Napolitano- Gio. Battista Spinelli Princ. di Cariati per Nilo- F. Giuseppantonio Comm. Francone per Montagna- Gennaro De Maio Duca di San Pietro per Montagna- Vincenzo Capecelatro Duca di Siano per Capoana- Gio. Battista Albertini Princ. di Cimitile per Portanuova- Andrea di Gennaro March. D&#8217;Auletta per Porto &#8211; Giuseppe Califano per lo Popolo. Dedicano. Offrono.<br \/>\nConsacrano- nell&#8217;Anno di nostra Era- MDCCLXXV.-<br \/>\nIl foglio N\u00b0 19 contiene le scale grafiche in pertiche napoletane, piedi parigini, piedi di Londra, palmi romani. I fogli N.i 24-34 contengono una &#8220;Veduta scenografica a ponente della Citt\u00e0 di Napoli in Campagna Felice&#8221; la &#8220;Spiegazione storiografica dell&#8217;antico e del moderno della citt\u00e0 di Napoli&#8221; e notizie sulla costruzione della carta. Il foglio N\u00b0 35 contiene tre iscrizioni greche tratte dal vol. III del &#8220;Corpus Inscriptionum Graecarum&#8221; N.i 5788, 5805, 5823 nella parte che si riferisce alla Magna Grecia. Due copie (la copia \u00e8 il documento n. 2) alla prima delle quali \u00e8 annessa la &#8220;Topografia dell&#8217;Agro Napoletano con le sue adiacenze. Delineata dal R. Geografo G. A. Rizzi Zannoni MDCCXCIII&#8221; alla scala approssimativa di 1:50.000 artistica ed accurata incisione in rame, su la quale \u00e8 stato tracciato a mano il quadro d&#8217;unione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grande carta in 35 fogli incisa su rame. L&#8217;esecuzione di questa carta venne decretata nel 1750 e commessa a G. Carafa Duca di Noja il quale fu assistito dal &#8220;gromatico Vanti che ne form\u00f2 l&#8217;intera delineazione geometrica&#8221;; l&#8217;incisione in rame venne affidata ai Prof.i Campana, Aloja e Lamarra. Morto il Carafa l&#8217;opera rimase interrotta; essa [&hellip;]<\/p>\n","protected":false},"featured_media":452411,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[191,447],"product_tag":[334],"class_list":{"0":"post-315982","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-carte-antiche","7":"product_cat-tecnica_risoluzione_carta_antica","8":"product_tag-carta-antica","10":"first","11":"instock","12":"downloadable","13":"virtual","14":"sold-individually","15":"taxable","16":"purchasable","17":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MAPPA TOPOGRAFICA DELLA CITTA&#039; DI NAPOLI E DE&#039; SUOI CONTORNI - FOGLIO 6. - Istituto Geografico Militare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/376034\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MAPPA TOPOGRAFICA DELLA CITTA&#039; DI NAPOLI E DE&#039; SUOI CONTORNI - FOGLIO 6. - Istituto Geografico Militare\" \/>\n<meta property=\"og:description\" content=\"Grande carta in 35 fogli incisa su rame. L&#8217;esecuzione di questa carta venne decretata nel 1750 e commessa a G. Carafa Duca di Noja il quale fu assistito dal &#8220;gromatico Vanti che ne form\u00f2 l&#8217;intera delineazione geometrica&#8221;; l&#8217;incisione in rame venne affidata ai Prof.i Campana, Aloja e Lamarra. Morto il Carafa l&#8217;opera rimase interrotta; essa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/376034\/\" \/>\n<meta property=\"og:site_name\" content=\"Istituto Geografico Militare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-21T03:09:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/CA006874.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"751\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/376034\/\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/376034\/\",\"name\":\"MAPPA TOPOGRAFICA DELLA CITTA' DI NAPOLI E DE' SUOI CONTORNI - FOGLIO 6. - Istituto Geografico Militare\",\"isPartOf\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/376034\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/376034\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/CA006874.jpg\",\"datePublished\":\"2025-06-25T06:48:48+00:00\",\"dateModified\":\"2026-04-21T03:09:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/376034\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/376034\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/376034\/#primaryimage\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/CA006874.jpg\",\"contentUrl\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/CA006874.jpg\",\"width\":1000,\"height\":751},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/376034\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/igmi.esercito.difesa.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/igmi.esercito.difesa.it\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MAPPA TOPOGRAFICA DELLA CITTA&#8217; DI NAPOLI E DE&#8217; SUOI CONTORNI &#8211; FOGLIO 6.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#website\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/en\/\",\"name\":\"Istituto Geografico Militare\",\"description\":\"Ente cartografico dello stato\",\"publisher\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/igmi.esercito.difesa.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#organization\",\"name\":\"Istituto Geografico Militare\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp\",\"contentUrl\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp\",\"width\":1320,\"height\":1696,\"caption\":\"Istituto Geografico Militare\"},\"image\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MAPPA TOPOGRAFICA DELLA CITTA' DI NAPOLI E DE' SUOI CONTORNI - FOGLIO 6. - Istituto Geografico Militare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/376034\/","og_locale":"en_US","og_type":"article","og_title":"MAPPA TOPOGRAFICA DELLA CITTA' DI NAPOLI E DE' SUOI CONTORNI - FOGLIO 6. - Istituto Geografico Militare","og_description":"Grande carta in 35 fogli incisa su rame. L&#8217;esecuzione di questa carta venne decretata nel 1750 e commessa a G. Carafa Duca di Noja il quale fu assistito dal &#8220;gromatico Vanti che ne form\u00f2 l&#8217;intera delineazione geometrica&#8221;; l&#8217;incisione in rame venne affidata ai Prof.i Campana, Aloja e Lamarra. Morto il Carafa l&#8217;opera rimase interrotta; essa [&hellip;]","og_url":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/376034\/","og_site_name":"Istituto Geografico Militare","article_modified_time":"2026-04-21T03:09:02+00:00","og_image":[{"width":1000,"height":751,"url":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/CA006874.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/376034\/","url":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/376034\/","name":"MAPPA TOPOGRAFICA DELLA CITTA' DI NAPOLI E DE' SUOI CONTORNI - FOGLIO 6. - Istituto Geografico Militare","isPartOf":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/376034\/#primaryimage"},"image":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/376034\/#primaryimage"},"thumbnailUrl":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/CA006874.jpg","datePublished":"2025-06-25T06:48:48+00:00","dateModified":"2026-04-21T03:09:02+00:00","breadcrumb":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/376034\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/376034\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/376034\/#primaryimage","url":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/CA006874.jpg","contentUrl":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/CA006874.jpg","width":1000,"height":751},{"@type":"BreadcrumbList","@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/376034\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/igmi.esercito.difesa.it\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/igmi.esercito.difesa.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"MAPPA TOPOGRAFICA DELLA CITTA&#8217; DI NAPOLI E DE&#8217; SUOI CONTORNI &#8211; FOGLIO 6."}]},{"@type":"WebSite","@id":"https:\/\/igmi.esercito.difesa.it\/en\/#website","url":"https:\/\/igmi.esercito.difesa.it\/en\/","name":"Istituto Geografico Militare","description":"Ente cartografico dello stato","publisher":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/igmi.esercito.difesa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/igmi.esercito.difesa.it\/en\/#organization","name":"Istituto Geografico Militare","url":"https:\/\/igmi.esercito.difesa.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp","contentUrl":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp","width":1320,"height":1696,"caption":"Istituto Geografico Militare"},"image":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product\/315982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/media\/452411"}],"wp:attachment":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/media?parent=315982"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product_brand?post=315982"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product_cat?post=315982"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product_tag?post=315982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}