{"id":33721,"date":"2025-06-14T06:18:31","date_gmt":"2025-06-14T04:18:31","guid":{"rendered":"https:\/\/igmi.esercito.difesa.it\/prodotto\/8964\/"},"modified":"2026-02-20T23:19:47","modified_gmt":"2026-02-20T22:19:47","slug":"8964","status":"publish","type":"product","link":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/8964\/","title":{"rendered":"057315 &#8211; CASALE MONFERRATO"},"content":{"rendered":"<p>057315 &#8211; CASALE MONFERRATO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>057315 &#8211; CASALE MONFERRATO<\/p>\n","protected":false},"featured_media":33714,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[220],"product_tag":[388],"class_list":{"0":"post-33721","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-vertici-trigonometrici","7":"product_tag-elemento-geodetico","9":"first","10":"instock","11":"downloadable","12":"virtual","13":"sold-individually","14":"taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>057315 - CASALE MONFERRATO - Istituto Geografico Militare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/8964\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"057315 - CASALE MONFERRATO - Istituto Geografico Militare\" \/>\n<meta property=\"og:description\" content=\"057315 &#8211; CASALE MONFERRATO\" \/>\n<meta property=\"og:url\" content=\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/8964\/\" \/>\n<meta property=\"og:site_name\" content=\"Istituto Geografico Militare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-20T22:19:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M057315-028592.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"315\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/8964\/\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/8964\/\",\"name\":\"057315 - CASALE MONFERRATO - Istituto Geografico Militare\",\"isPartOf\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/8964\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/8964\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M057315-028592.jpg\",\"datePublished\":\"2025-06-14T04:18:31+00:00\",\"dateModified\":\"2026-02-20T22:19:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/8964\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/8964\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/8964\/#primaryimage\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M057315-028592.jpg\",\"contentUrl\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M057315-028592.jpg\",\"width\":315,\"height\":315},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/8964\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/igmi.esercito.difesa.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/igmi.esercito.difesa.it\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"057315 &#8211; CASALE MONFERRATO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#website\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/en\/\",\"name\":\"Istituto Geografico Militare\",\"description\":\"Ente cartografico dello stato\",\"publisher\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/igmi.esercito.difesa.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#organization\",\"name\":\"Istituto Geografico Militare\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp\",\"contentUrl\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp\",\"width\":1320,\"height\":1696,\"caption\":\"Istituto Geografico Militare\"},\"image\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"057315 - CASALE MONFERRATO - Istituto Geografico Militare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/8964\/","og_locale":"en_US","og_type":"article","og_title":"057315 - CASALE MONFERRATO - Istituto Geografico Militare","og_description":"057315 &#8211; CASALE MONFERRATO","og_url":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/8964\/","og_site_name":"Istituto Geografico Militare","article_modified_time":"2026-02-20T22:19:47+00:00","og_image":[{"width":315,"height":315,"url":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M057315-028592.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/8964\/","url":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/8964\/","name":"057315 - CASALE MONFERRATO - Istituto Geografico Militare","isPartOf":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/8964\/#primaryimage"},"image":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/8964\/#primaryimage"},"thumbnailUrl":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M057315-028592.jpg","datePublished":"2025-06-14T04:18:31+00:00","dateModified":"2026-02-20T22:19:47+00:00","breadcrumb":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/8964\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/8964\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/8964\/#primaryimage","url":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M057315-028592.jpg","contentUrl":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/M057315-028592.jpg","width":315,"height":315},{"@type":"BreadcrumbList","@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/8964\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/igmi.esercito.difesa.it\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/igmi.esercito.difesa.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"057315 &#8211; CASALE MONFERRATO"}]},{"@type":"WebSite","@id":"https:\/\/igmi.esercito.difesa.it\/en\/#website","url":"https:\/\/igmi.esercito.difesa.it\/en\/","name":"Istituto Geografico Militare","description":"Ente cartografico dello stato","publisher":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/igmi.esercito.difesa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/igmi.esercito.difesa.it\/en\/#organization","name":"Istituto Geografico Militare","url":"https:\/\/igmi.esercito.difesa.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp","contentUrl":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp","width":1320,"height":1696,"caption":"Istituto Geografico Militare"},"image":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product\/33721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/media\/33714"}],"wp:attachment":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/media?parent=33721"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product_brand?post=33721"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product_cat?post=33721"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product_tag?post=33721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}