{"id":95529,"date":"2025-06-17T02:06:25","date_gmt":"2025-06-17T00:06:25","guid":{"rendered":"https:\/\/igmi.esercito.difesa.it\/prodotto\/37633\/"},"modified":"2026-02-16T21:44:19","modified_gmt":"2026-02-16T20:44:19","slug":"37633","status":"publish","type":"product","link":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/37633\/","title":{"rendered":"0089#_###_098# &#8211; S.S. 103 &#8211; KM 96+400"},"content":{"rendered":"<p>0089#_###_098# &#8211; S.S. 103 &#8211; KM 96+400 &#8211; Muro di sottoscarpa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>0089#_###_098# &#8211; S.S. 103 &#8211; KM 96+400 &#8211; Muro di sottoscarpa<\/p>\n","protected":false},"featured_media":95523,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[203,218],"product_tag":[388],"class_list":{"0":"post-95529","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-capisaldi-livellazione","7":"product_cat-tecnica_prezzo_caposaldi_livellazione","8":"product_tag-elemento-geodetico","10":"first","11":"instock","12":"downloadable","13":"virtual","14":"sold-individually","15":"taxable","16":"purchasable","17":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>0089#_###_098# - S.S. 103 - KM 96+400 - Istituto Geografico Militare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/37633\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"0089#_###_098# - S.S. 103 - KM 96+400 - Istituto Geografico Militare\" \/>\n<meta property=\"og:description\" content=\"0089#_###_098# &#8211; S.S. 103 &#8211; KM 96+400 &#8211; Muro di sottoscarpa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/37633\/\" \/>\n<meta property=\"og:site_name\" content=\"Istituto Geografico Militare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-16T20:44:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/0089-_-_098-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/37633\/\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/37633\/\",\"name\":\"0089#_###_098# - S.S. 103 - KM 96+400 - Istituto Geografico Militare\",\"isPartOf\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/37633\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/37633\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/0089-_-_098-.jpg\",\"datePublished\":\"2025-06-17T00:06:25+00:00\",\"dateModified\":\"2026-02-16T20:44:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/37633\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/37633\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/37633\/#primaryimage\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/0089-_-_098-.jpg\",\"contentUrl\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/0089-_-_098-.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/37633\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/igmi.esercito.difesa.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/igmi.esercito.difesa.it\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"0089#_###_098# &#8211; S.S. 103 &#8211; KM 96+400\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#website\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/en\/\",\"name\":\"Istituto Geografico Militare\",\"description\":\"Ente cartografico dello stato\",\"publisher\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/igmi.esercito.difesa.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#organization\",\"name\":\"Istituto Geografico Militare\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp\",\"contentUrl\":\"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp\",\"width\":1320,\"height\":1696,\"caption\":\"Istituto Geografico Militare\"},\"image\":{\"@id\":\"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"0089#_###_098# - S.S. 103 - KM 96+400 - Istituto Geografico Militare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/37633\/","og_locale":"en_US","og_type":"article","og_title":"0089#_###_098# - S.S. 103 - KM 96+400 - Istituto Geografico Militare","og_description":"0089#_###_098# &#8211; S.S. 103 &#8211; KM 96+400 &#8211; Muro di sottoscarpa","og_url":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/37633\/","og_site_name":"Istituto Geografico Militare","article_modified_time":"2026-02-16T20:44:19+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/0089-_-_098-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/37633\/","url":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/37633\/","name":"0089#_###_098# - S.S. 103 - KM 96+400 - Istituto Geografico Militare","isPartOf":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/37633\/#primaryimage"},"image":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/37633\/#primaryimage"},"thumbnailUrl":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/0089-_-_098-.jpg","datePublished":"2025-06-17T00:06:25+00:00","dateModified":"2026-02-16T20:44:19+00:00","breadcrumb":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/37633\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/37633\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/37633\/#primaryimage","url":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/0089-_-_098-.jpg","contentUrl":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/0089-_-_098-.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/igmi.esercito.difesa.it\/en\/prodotto\/37633\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/igmi.esercito.difesa.it\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/igmi.esercito.difesa.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"0089#_###_098# &#8211; S.S. 103 &#8211; KM 96+400"}]},{"@type":"WebSite","@id":"https:\/\/igmi.esercito.difesa.it\/en\/#website","url":"https:\/\/igmi.esercito.difesa.it\/en\/","name":"Istituto Geografico Militare","description":"Ente cartografico dello stato","publisher":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/igmi.esercito.difesa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/igmi.esercito.difesa.it\/en\/#organization","name":"Istituto Geografico Militare","url":"https:\/\/igmi.esercito.difesa.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp","contentUrl":"https:\/\/igmi.esercito.difesa.it\/wp-content\/uploads\/2025\/04\/Logo-igm.webp","width":1320,"height":1696,"caption":"Istituto Geografico Militare"},"image":{"@id":"https:\/\/igmi.esercito.difesa.it\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product\/95529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/media\/95523"}],"wp:attachment":[{"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/media?parent=95529"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product_brand?post=95529"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product_cat?post=95529"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/igmi.esercito.difesa.it\/en\/wp-json\/wp\/v2\/product_tag?post=95529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}